{"id":475,"count":0,"description":"Biblioth\u00e8que de ressources fiables, outils de suivi de sant\u00e9, et recommandations de livres et de podcasts.\r\n","link":"https:\/\/www.lamaisondesante.com\/forum\/question-category\/ressources-et-outils-de-sante\/","name":"Ressources et Outils de Sant\u00e9","slug":"ressources-et-outils-de-sante","taxonomy":"question-category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/www.lamaisondesante.com\/forum\/wp-json\/wp\/v2\/question-category\/475","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lamaisondesante.com\/forum\/wp-json\/wp\/v2\/question-category"}],"about":[{"href":"https:\/\/www.lamaisondesante.com\/forum\/wp-json\/wp\/v2\/taxonomies\/question-category"}],"wp:post_type":[{"href":"https:\/\/www.lamaisondesante.com\/forum\/wp-json\/wp\/v2\/question?question-category=475"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}